{"id":7494,"date":"2021-09-23T11:40:31","date_gmt":"2021-09-23T11:40:31","guid":{"rendered":"https:\/\/www.inmobiliariacoll.com\/property\/reformada-casa-de-piedra-con-precioso-jardin-y-piscina-en-soller\/"},"modified":"2021-09-23T11:45:02","modified_gmt":"2021-09-23T11:45:02","slug":"reformada-casa-de-piedra-con-precioso-jardin-y-piscina-en-soller","status":"publish","type":"property","link":"https:\/\/www.inmobiliariacoll.com\/ca\/property\/reformada-casa-de-piedra-con-precioso-jardin-y-piscina-en-soller\/","title":{"rendered":"Reformada casa de pedra amb preci\u00f3s jard\u00ed i piscina a S\u00f3ller"},"content":{"rendered":"\n<p>Aquesta bonica casa de pedra se situa als afores de S\u00f3ller i disposa de dos accessos. Recentment reformada en estil tradicional es distribueix en planta baixa amb cuina-office, sal\u00f3-menjador amb llar de foc i estufa de llenya, una habitaci\u00f3 amb lavabo, garatge i traster. L&#8217;entres\u00f2l i la primera planta disposen de bugaderia, 3 habitacions i dos banys en suite. A destacar la planta superior de la casa on es troba l&#8217;habitaci\u00f3 principal amb doble vestidor, gran bany amb banyera i dutxa i bonica terrassa amb fant\u00e0stiques vistes. A l&#8217;exterior trobem un bonic jard\u00ed amb piscina, palmeres, hort amb arbres fruiters, caseta de convidats (amb cuina, habitaci\u00f3 i bany), terrasses i \u00e0mplia zona de p\u00e0rquing. Sens dubte una bonica propietat per gaudir de l&#8217;exterior i de les vistes de S\u00f3ller. La propietat disposa de llic\u00e8ncia vacacional<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Aquesta bonica casa de pedra se situa als afores de S\u00f3ller i disposa de dos accessos. Recentment reformada en estil tradicional es distribueix en planta baixa amb cuina-office, sal\u00f3-menjador amb llar de foc i estufa de llenya, una habitaci\u00f3 amb lavabo, garatge i traster. L&#8217;entres\u00f2l i la primera planta disposen de bugaderia, 3 habitacions i [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":7482,"parent":0,"menu_order":0,"template":"","property_type":[138],"property_status":[150],"property_feature":[79,91,94],"property_label":[],"property_country":[158],"property_state":[160],"property_city":[175],"property_area":[],"class_list":["post-7494","property","type-property","status-publish","has-post-thumbnail","hentry","property_type-casa-ca","property_status-venda","property_feature-air-conditioning-ca","property_feature-laundry-ca","property_feature-lawn-ca","property_country-espanya","property_state-mallorca-ca","property_city-soller-ca"],"property_meta":{"fave_property_price":["1750000"],"fave_property_size":["450"],"fave_property_land":["2700"],"fave_property_bedrooms":["5"],"fave_property_bathrooms":["4"],"fave_property_id":["20510"],"fave_property_map":["1"],"fave_property_location":["25.68654,-80.431345,15"],"houzez_geolocation_lat":["25.68654"],"houzez_geolocation_long":["-80.431345"],"fave_property_map_street_view":["hide"],"fave_featured":["0"],"fave_loggedintoview":["0"],"fave_agent_display_option":["author_info"],"fave_agents":["-1"],"fave_property_agency":["-1"],"fave_prop_homeslider":["no"],"fave_single_top_area":["global"],"fave_single_content_area":["global"],"additional_features":["a:2:{i:0;a:1:{s:29:\"fave_additional_feature_title\";s:9:\"Garaje si\";}i:1;a:1:{s:29:\"fave_additional_feature_title\";s:21:\"aire acondicionado si\";}}"],"rs_page_bg_color":[""],"houzez_manual_expire":["0"],"_houzez_expiration_date_status":["saved"],"_wpml_media_duplicate":["1"],"_wpml_media_featured":["1"],"_thumbnail_id":["7482"],"_edit_lock":["1632397559:3"],"_last_translation_edit_mode":["native-editor"],"_edit_last":["3"],"fave_property_images":["7489","7481","7485","7445","7449","7453","7473","7469","7465","7461","7457","7433","7437","7441","7429"],"houzez_total_property_views":["185"],"houzez_views_by_date":["a:61:{s:10:\"01-15-2025\";i:1;s:10:\"01-17-2025\";i:1;s:10:\"01-21-2025\";i:1;s:10:\"01-30-2025\";i:1;s:10:\"02-02-2025\";i:1;s:10:\"02-11-2025\";i:2;s:10:\"02-12-2025\";i:1;s:10:\"02-15-2025\";i:1;s:10:\"02-16-2025\";i:1;s:10:\"02-18-2025\";i:1;s:10:\"02-20-2025\";i:1;s:10:\"02-22-2025\";i:1;s:10:\"02-24-2025\";i:1;s:10:\"02-27-2025\";i:1;s:10:\"03-01-2025\";i:1;s:10:\"03-03-2025\";i:1;s:10:\"03-06-2025\";i:2;s:10:\"03-27-2025\";i:1;s:10:\"04-04-2025\";i:1;s:10:\"04-06-2025\";i:1;s:10:\"05-01-2025\";i:1;s:10:\"05-02-2025\";i:1;s:10:\"05-22-2025\";i:1;s:10:\"05-26-2025\";i:1;s:10:\"06-03-2025\";i:1;s:10:\"06-04-2025\";i:2;s:10:\"07-19-2025\";i:1;s:10:\"08-12-2025\";i:1;s:10:\"08-26-2025\";i:1;s:10:\"08-28-2025\";i:1;s:10:\"09-02-2025\";i:1;s:10:\"09-04-2025\";i:1;s:10:\"09-11-2025\";i:2;s:10:\"09-12-2025\";i:1;s:10:\"09-14-2025\";i:1;s:10:\"09-23-2025\";i:1;s:10:\"09-25-2025\";i:1;s:10:\"09-28-2025\";i:1;s:10:\"10-02-2025\";i:1;s:10:\"10-03-2025\";i:1;s:10:\"10-06-2025\";i:1;s:10:\"10-08-2025\";i:1;s:10:\"10-10-2025\";i:2;s:10:\"10-12-2025\";i:1;s:10:\"10-13-2025\";i:1;s:10:\"10-14-2025\";i:1;s:10:\"10-16-2025\";i:1;s:10:\"10-19-2025\";i:1;s:10:\"10-20-2025\";i:1;s:10:\"10-21-2025\";i:1;s:10:\"10-25-2025\";i:1;s:10:\"10-29-2025\";i:1;s:10:\"11-10-2025\";i:1;s:10:\"11-13-2025\";i:1;s:10:\"11-15-2025\";i:1;s:10:\"11-20-2025\";i:1;s:10:\"12-15-2025\";i:1;s:10:\"01-11-2026\";i:1;s:10:\"01-18-2026\";i:1;s:10:\"02-21-2026\";i:1;s:10:\"03-02-2026\";i:1;}"],"houzez_recently_viewed":["2026-03-02 14:16:16"]},"_links":{"self":[{"href":"https:\/\/www.inmobiliariacoll.com\/ca\/wp-json\/wp\/v2\/properties\/7494","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.inmobiliariacoll.com\/ca\/wp-json\/wp\/v2\/properties"}],"about":[{"href":"https:\/\/www.inmobiliariacoll.com\/ca\/wp-json\/wp\/v2\/types\/property"}],"author":[{"embeddable":true,"href":"https:\/\/www.inmobiliariacoll.com\/ca\/wp-json\/wp\/v2\/users\/3"}],"version-history":[{"count":1,"href":"https:\/\/www.inmobiliariacoll.com\/ca\/wp-json\/wp\/v2\/properties\/7494\/revisions"}],"predecessor-version":[{"id":7498,"href":"https:\/\/www.inmobiliariacoll.com\/ca\/wp-json\/wp\/v2\/properties\/7494\/revisions\/7498"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.inmobiliariacoll.com\/ca\/wp-json\/wp\/v2\/media\/7482"}],"wp:attachment":[{"href":"https:\/\/www.inmobiliariacoll.com\/ca\/wp-json\/wp\/v2\/media?parent=7494"}],"wp:term":[{"taxonomy":"property_type","embeddable":true,"href":"https:\/\/www.inmobiliariacoll.com\/ca\/wp-json\/wp\/v2\/property_type?post=7494"},{"taxonomy":"property_status","embeddable":true,"href":"https:\/\/www.inmobiliariacoll.com\/ca\/wp-json\/wp\/v2\/property_status?post=7494"},{"taxonomy":"property_feature","embeddable":true,"href":"https:\/\/www.inmobiliariacoll.com\/ca\/wp-json\/wp\/v2\/property_feature?post=7494"},{"taxonomy":"property_label","embeddable":true,"href":"https:\/\/www.inmobiliariacoll.com\/ca\/wp-json\/wp\/v2\/property_label?post=7494"},{"taxonomy":"property_country","embeddable":true,"href":"https:\/\/www.inmobiliariacoll.com\/ca\/wp-json\/wp\/v2\/property_country?post=7494"},{"taxonomy":"property_state","embeddable":true,"href":"https:\/\/www.inmobiliariacoll.com\/ca\/wp-json\/wp\/v2\/property_state?post=7494"},{"taxonomy":"property_city","embeddable":true,"href":"https:\/\/www.inmobiliariacoll.com\/ca\/wp-json\/wp\/v2\/property_city?post=7494"},{"taxonomy":"property_area","embeddable":true,"href":"https:\/\/www.inmobiliariacoll.com\/ca\/wp-json\/wp\/v2\/property_area?post=7494"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}